


{"id":1207,"date":"2024-10-28T12:48:05","date_gmt":"2024-10-28T12:48:05","guid":{"rendered":"https:\/\/gyn-munich.com\/?p=1207"},"modified":"2025-07-03T10:01:49","modified_gmt":"2025-07-03T10:01:49","slug":"gynaekologisches-krebszentrum","status":"publish","type":"post","link":"https:\/\/gyn-munich.com\/en\/gynaekologisches-krebszentrum\/","title":{"rendered":"Gynaecological cancer center"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Sektion Brust chirurgie&#8220; _builder_version=&#8220;4.18.0&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_row admin_label=&#8220;Zeile Brust Chirurgie&#8220; _builder_version=&#8220;4.18.0&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Gyn\u00e4kologisches Krebszentrum&#8220; _builder_version=&#8220;4.27.2&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Die h\u00e4ufigsten Krebserkrankungen des weiblichen Genitaltrakts betreffen die Geb\u00e4rmutter, den Geb\u00e4rmutterhals und die Eierst\u00f6cke. F\u00fcr die betroffenen Frauen und ihr Umfeld stellt die Diagnose oft eine tiefgreifende Ver\u00e4nderung dar. Umso wichtiger ist es uns, Patientinnen in dieser Situation umfassend zu betreuen und zu therapieren.<\/p>\n<p>In unserem interdisziplin\u00e4ren gyn\u00e4kologischen Krebszentrum setzen wir auf die Erfahrung von Experten unterschiedlicher Fachrichtungen, um eine individuell abgestimmte und optimale Behandlung zu gew\u00e4hrleisten. Dabei legen wir gro\u00dfen Wert auf einen einf\u00fchlsamen und vertrauensvollen Umgang mit den Patientinnen.<\/p>\n<p>Die operative Behandlung ist meist der erste und entscheidende Schritt in der Therapie gyn\u00e4kologischer Tumorenund prognostisch von besonderer Bedeutung.<\/p>\n<p>Minimal-invasive Techniken haben in vielen Bereichen die offene Chirurgie abgel\u00f6st, insbesondere bei Geb\u00e4rmutter- und Geb\u00e4rmutterhalskrebs. Diese Techniken erm\u00f6glichen es, das Ausma\u00df eines Eingriffs deutlich zu reduzieren, wie etwa durch die Anwendung der Sentinel-Lymphknoten-Technik. Hierbei werden nur die ersten Lymphknoten im Abflussgebiet des Tumors entfernt, was zu einer schnelleren Genesung und einer h\u00f6heren Lebensqualit\u00e4t f\u00fchrt.<\/p>\n<p>Bei jungen Patientinnen mit Kinderwunsch bieten wir in fr\u00fchen Krankheitsstadien auch fertilit\u00e4tserhaltende Operationen an, die gleichzeitig eine hohe onkologische Sicherheit gew\u00e4hrleisten.<\/p>\n<p>Unsere Klinik setzt modernste Technologien ein, wie das integrierte OP-System von Olympus und Karl Storz, die weltweit f\u00fchrend in der endoskopischen Medizintechnik sind. Wir sind zudem eines der wenigen Ausbildungszentren f\u00fcr minimal-invasive Chirurgie in Deutschland und das einzige in Bayern, mit Operateuren, die \u00fcber die h\u00f6chste Qualifikationsstufe MIC 3 verf\u00fcgen. Diese Zertifizierung garantiert h\u00f6chste Pr\u00e4zision und Sicherheit auch bei anspruchsvollsten Eingriffen.<\/p>\n<p><strong>Geb\u00e4rmutterhalskrebs (Zervixkarzinom)<\/strong><\/p>\n<p>Das Zervixkarzinom ist eine b\u00f6sartige Erkrankung des Geb\u00e4rmutterhalses, die h\u00e4ufig durch eine Infektion mit humanen Papillomviren (HPV) \u00a0verursacht wird. J\u00e4hrlich erkranken in Deutschland etwa 4.500 Frauen, wobei diese Zahl durch HPV-Impfung und Vorsorgeuntersuchungen r\u00fcckl\u00e4ufig ist. Die Therapie h\u00e4ngt vom Stadium der Erkrankung ab. In fr\u00fchen Stadien erfolgt in der Regel eine operative Behandlung, wie eine Konisation oder Hysterektomie, oft erg\u00e4nzt durch eine Lymphknotenentfernung. In fortgeschrittenen Stadien kommen Strahlen- und Chemotherapie zum Einsatz. Regelm\u00e4\u00dfige Vorsorgeuntersuchungen sind entscheidend, um fr\u00fche Stadien und Krebsvorstufen (CIN) rechtzeitig zu erkennen und zu behandeln.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Geb\u00e4rmutterkrebs (Endometriumkarzinom)<\/strong><\/p>\n<p>Das Endometriumkarzinom ist eine b\u00f6sartige Erkrankung der Geb\u00e4rmutterschleimhaut, von der in Deutschland j\u00e4hrlich etwa 12.000 Frauen betroffen sind, \u00fcberwiegend postmenopausale Patientinnen. Ein erstes Symptom ist oft eine unerwartete vaginale Blutung nach dem Ausbleiben der Menstruation. Die Diagnose erfolgt in der Regel minimalinvasiv durch eine Geb\u00e4rmutterspiegelung (Hysteroskopie) mit Gewebeentnahme. Die Therapie besteht meist in der operativen Entfernung der Geb\u00e4rmutter, der Eierst\u00f6cke und der Lymphknoten (Sentinel-Lymphonodektomie). Je nach Tumorstadium kann eine zus\u00e4tzliche Strahlen- oder Chemotherapie erforderlich sein.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Vertrauen Sie auf unsere Expertise \u2013 bei uns sind Sie in den besten H\u00e4nden.<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die h\u00e4ufigsten Krebserkrankungen des weiblichen Genitaltrakts betreffen die Geb\u00e4rmutter, den Geb\u00e4rmutterhals und die Eierst\u00f6cke. F\u00fcr die betroffenen Frauen und ihr Umfeld stellt die Diagnose oft eine tiefgreifende Ver\u00e4nderung dar. Umso wichtiger ist es uns, Patientinnen in dieser Situation umfassend zu betreuen und zu therapieren. In unserem interdisziplin\u00e4ren gyn\u00e4kologischen Krebszentrum setzen wir auf die Erfahrung von [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1267,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:paragraph -->\r\n<p>Wahre Sch\u00f6nheit kommt nicht nur von innen. Ihr \u00c4u\u00dferes ist f\u00fcr Ihr Selbstbild\u00a0genauso wichtig wie Ihre inneren Qualit\u00e4ten. Ein gutes Gef\u00fchl beim Anblick des\u00a0eigenen K\u00f6rpers wirkt sich positiv auf das seelische Gleichgewicht aus. Wer\u00a0sich sch\u00f6n f\u00fchlt, ist selbstbewusster und steigert damit seine Lebensqualit\u00e4t. Die plastische und \u00e4sthetische Chirurgie erf\u00fcllt also eine Aufgabe, die \u00fcber rein \u00e4u\u00dferliche Korrekturen weit hinausgeht. Das gilt f\u00fcr individuelle Ver\u00e4nderungsw\u00fcnsche (z. B. Brustvergr\u00f6\u00dferungen) genauso wie f\u00fcr medizinisch notwendige Eingriffe. Dazu z\u00e4hlen beispielsweise Brustverkleinerungen aufgrund von R\u00fcckenproblemen oder die \u201erekonstruktive\u201c Chirurgie, das hei\u00dft der Wiederaufbau der weiblichen Brust nach Unf\u00e4llen oder schweren Krebserkrankungen. Moderne Operationsverfahren haben es vielen Frauen erm\u00f6glicht, ihr Selbstwertgef\u00fchl wiederzufinden und ein neues Leben zu beginnen.<\/p>\r\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\r\n<p>Um Ihnen die besten\u00a0Therapien zu erm\u00f6glichen\u00a0haben wir uns mit\u00a0international anerkannten Kollegen zusammengeschlossen<\/p>\r\n<!-- \/wp:paragraph -->","_et_gb_content_width":"","footnotes":""},"categories":[14],"tags":[],"class_list":["post-1207","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-14"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gyn\u00e4kologisches Krebszentrum<\/title>\n<meta name=\"description\" content=\"Gyn\u00e4kologische Onkologie: Krebsbehandlung bei Geb\u00e4rmutter, Zervix &amp; Eierst\u00f6cken \u2013 individuell, minimal-invasiv &amp; MIC 3-zertifiziert in M\u00fcnchen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gyn-munich.com\/en\/gynaekologisches-krebszentrum\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gyn\u00e4kologisches Krebszentrum\" \/>\n<meta property=\"og:description\" content=\"Gyn\u00e4kologische Onkologie: Krebsbehandlung bei Geb\u00e4rmutter, Zervix &amp; Eierst\u00f6cken \u2013 individuell, minimal-invasiv &amp; MIC 3-zertifiziert in M\u00fcnchen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gyn-munich.com\/en\/gynaekologisches-krebszentrum\/\" \/>\n<meta property=\"og:site_name\" content=\"gyn-munich\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-28T12:48:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-03T10:01:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gyn-munich.com\/wp-content\/uploads\/2024\/10\/labor2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gyn-munich.com\\\/gynaekologisches-krebszentrum\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gyn-munich.com\\\/gynaekologisches-krebszentrum\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/gyn-munich.com\\\/de\\\/#\\\/schema\\\/person\\\/6598320df87431599906577de19a702c\"},\"headline\":\"Gyn\u00e4kologisches Krebszentrum\",\"datePublished\":\"2024-10-28T12:48:05+00:00\",\"dateModified\":\"2025-07-03T10:01:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gyn-munich.com\\\/gynaekologisches-krebszentrum\\\/\"},\"wordCount\":554,\"publisher\":{\"@id\":\"https:\\\/\\\/gyn-munich.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gyn-munich.com\\\/gynaekologisches-krebszentrum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gyn-munich.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/labor2-1.jpg\",\"articleSection\":[\"5\"],\"inLanguage\":\"en-US\"},{\"@type\":[\"WebPage\",\"MedicalWebPage\"],\"@id\":\"https:\\\/\\\/gyn-munich.com\\\/gynaekologisches-krebszentrum\\\/\",\"url\":\"https:\\\/\\\/gyn-munich.com\\\/gynaekologisches-krebszentrum\\\/\",\"name\":\"Gyn\u00e4kologisches Krebszentrum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gyn-munich.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gyn-munich.com\\\/gynaekologisches-krebszentrum\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gyn-munich.com\\\/gynaekologisches-krebszentrum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gyn-munich.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/labor2-1.jpg\",\"datePublished\":\"2024-10-28T12:48:05+00:00\",\"dateModified\":\"2025-07-03T10:01:49+00:00\",\"description\":\"Gyn\u00e4kologische Onkologie: Krebsbehandlung bei Geb\u00e4rmutter, Zervix & Eierst\u00f6cken \u2013 individuell, minimal-invasiv & MIC 3-zertifiziert in M\u00fcnchen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gyn-munich.com\\\/gynaekologisches-krebszentrum\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gyn-munich.com\\\/gynaekologisches-krebszentrum\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/gyn-munich.com\\\/gynaekologisches-krebszentrum\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gyn-munich.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/labor2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/gyn-munich.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/labor2-1.jpg\",\"width\":400,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gyn-munich.com\\\/gynaekologisches-krebszentrum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/gyn-munich.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gyn\u00e4kologisches Krebszentrum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gyn-munich.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/gyn-munich.com\\\/de\\\/\",\"name\":\"gyn-munich\",\"description\":\"gynecologic surgery\",\"publisher\":{\"@id\":\"https:\\\/\\\/gyn-munich.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gyn-munich.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gyn-munich.com\\\/de\\\/#organization\",\"name\":\"gyn-munich\",\"url\":\"https:\\\/\\\/gyn-munich.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/gyn-munich.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gyn-munich.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/gyn_munich_logo.png\",\"contentUrl\":\"https:\\\/\\\/gyn-munich.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/gyn_munich_logo.png\",\"width\":511,\"height\":152,\"caption\":\"gyn-munich\"},\"image\":{\"@id\":\"https:\\\/\\\/gyn-munich.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gyn-munich.com\\\/de\\\/#\\\/schema\\\/person\\\/6598320df87431599906577de19a702c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61b634faf0acc594a1db116de7c555dcac6ef692356275ded46cfc5671d28bcc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61b634faf0acc594a1db116de7c555dcac6ef692356275ded46cfc5671d28bcc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61b634faf0acc594a1db116de7c555dcac6ef692356275ded46cfc5671d28bcc?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/gyn-munich.com\"],\"url\":\"https:\\\/\\\/gyn-munich.com\\\/en\\\/author\\\/w01cb7db\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gynaecological cancer center","description":"Gyn\u00e4kologische Onkologie: Krebsbehandlung bei Geb\u00e4rmutter, Zervix & Eierst\u00f6cken \u2013 individuell, minimal-invasiv & MIC 3-zertifiziert in M\u00fcnchen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gyn-munich.com\/en\/gynaekologisches-krebszentrum\/","og_locale":"en_US","og_type":"article","og_title":"Gyn\u00e4kologisches Krebszentrum","og_description":"Gyn\u00e4kologische Onkologie: Krebsbehandlung bei Geb\u00e4rmutter, Zervix & Eierst\u00f6cken \u2013 individuell, minimal-invasiv & MIC 3-zertifiziert in M\u00fcnchen.","og_url":"https:\/\/gyn-munich.com\/en\/gynaekologisches-krebszentrum\/","og_site_name":"gyn-munich","article_published_time":"2024-10-28T12:48:05+00:00","article_modified_time":"2025-07-03T10:01:49+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/gyn-munich.com\/wp-content\/uploads\/2024\/10\/labor2-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gyn-munich.com\/gynaekologisches-krebszentrum\/#article","isPartOf":{"@id":"https:\/\/gyn-munich.com\/gynaekologisches-krebszentrum\/"},"author":{"name":"admin","@id":"https:\/\/gyn-munich.com\/de\/#\/schema\/person\/6598320df87431599906577de19a702c"},"headline":"Gyn\u00e4kologisches Krebszentrum","datePublished":"2024-10-28T12:48:05+00:00","dateModified":"2025-07-03T10:01:49+00:00","mainEntityOfPage":{"@id":"https:\/\/gyn-munich.com\/gynaekologisches-krebszentrum\/"},"wordCount":554,"publisher":{"@id":"https:\/\/gyn-munich.com\/de\/#organization"},"image":{"@id":"https:\/\/gyn-munich.com\/gynaekologisches-krebszentrum\/#primaryimage"},"thumbnailUrl":"https:\/\/gyn-munich.com\/wp-content\/uploads\/2024\/10\/labor2-1.jpg","articleSection":["5"],"inLanguage":"en-US"},{"@type":["WebPage","MedicalWebPage"],"@id":"https:\/\/gyn-munich.com\/gynaekologisches-krebszentrum\/","url":"https:\/\/gyn-munich.com\/gynaekologisches-krebszentrum\/","name":"Gynaecological cancer center","isPartOf":{"@id":"https:\/\/gyn-munich.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gyn-munich.com\/gynaekologisches-krebszentrum\/#primaryimage"},"image":{"@id":"https:\/\/gyn-munich.com\/gynaekologisches-krebszentrum\/#primaryimage"},"thumbnailUrl":"https:\/\/gyn-munich.com\/wp-content\/uploads\/2024\/10\/labor2-1.jpg","datePublished":"2024-10-28T12:48:05+00:00","dateModified":"2025-07-03T10:01:49+00:00","description":"Gyn\u00e4kologische Onkologie: Krebsbehandlung bei Geb\u00e4rmutter, Zervix & Eierst\u00f6cken \u2013 individuell, minimal-invasiv & MIC 3-zertifiziert in M\u00fcnchen.","breadcrumb":{"@id":"https:\/\/gyn-munich.com\/gynaekologisches-krebszentrum\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gyn-munich.com\/gynaekologisches-krebszentrum\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gyn-munich.com\/gynaekologisches-krebszentrum\/#primaryimage","url":"https:\/\/gyn-munich.com\/wp-content\/uploads\/2024\/10\/labor2-1.jpg","contentUrl":"https:\/\/gyn-munich.com\/wp-content\/uploads\/2024\/10\/labor2-1.jpg","width":400,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/gyn-munich.com\/gynaekologisches-krebszentrum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/gyn-munich.com\/de\/"},{"@type":"ListItem","position":2,"name":"Gyn\u00e4kologisches Krebszentrum"}]},{"@type":"WebSite","@id":"https:\/\/gyn-munich.com\/de\/#website","url":"https:\/\/gyn-munich.com\/de\/","name":"gyn-munich","description":"gynecologic surgery","publisher":{"@id":"https:\/\/gyn-munich.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gyn-munich.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/gyn-munich.com\/de\/#organization","name":"gyn-munich","url":"https:\/\/gyn-munich.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gyn-munich.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/gyn-munich.com\/wp-content\/uploads\/2022\/06\/gyn_munich_logo.png","contentUrl":"https:\/\/gyn-munich.com\/wp-content\/uploads\/2022\/06\/gyn_munich_logo.png","width":511,"height":152,"caption":"gyn-munich"},"image":{"@id":"https:\/\/gyn-munich.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/gyn-munich.com\/de\/#\/schema\/person\/6598320df87431599906577de19a702c","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/61b634faf0acc594a1db116de7c555dcac6ef692356275ded46cfc5671d28bcc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/61b634faf0acc594a1db116de7c555dcac6ef692356275ded46cfc5671d28bcc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61b634faf0acc594a1db116de7c555dcac6ef692356275ded46cfc5671d28bcc?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/gyn-munich.com"],"url":"https:\/\/gyn-munich.com\/en\/author\/w01cb7db\/"}]}},"_links":{"self":[{"href":"https:\/\/gyn-munich.com\/en\/wp-json\/wp\/v2\/posts\/1207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gyn-munich.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gyn-munich.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gyn-munich.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gyn-munich.com\/en\/wp-json\/wp\/v2\/comments?post=1207"}],"version-history":[{"count":4,"href":"https:\/\/gyn-munich.com\/en\/wp-json\/wp\/v2\/posts\/1207\/revisions"}],"predecessor-version":[{"id":1212,"href":"https:\/\/gyn-munich.com\/en\/wp-json\/wp\/v2\/posts\/1207\/revisions\/1212"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gyn-munich.com\/en\/wp-json\/wp\/v2\/media\/1267"}],"wp:attachment":[{"href":"https:\/\/gyn-munich.com\/en\/wp-json\/wp\/v2\/media?parent=1207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gyn-munich.com\/en\/wp-json\/wp\/v2\/categories?post=1207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gyn-munich.com\/en\/wp-json\/wp\/v2\/tags?post=1207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}